{"id":2707,"date":"2024-09-26T09:22:16","date_gmt":"2024-09-26T09:22:16","guid":{"rendered":"https:\/\/bdbmetal.com\/urun\/profiled-square-model-trash-can\/"},"modified":"2025-11-04T15:55:37","modified_gmt":"2025-11-04T15:55:37","slug":"profiled-square-model-trash-can","status":"publish","type":"product","link":"https:\/\/bdbmetal.com\/en\/profiled-square-model-trash-can\/","title":{"rendered":"Profiled Square Model Trash Can"},"content":{"rendered":"<h3>Metal Series Outdoor Product Information (Profiled Square Model Trash Can)<\/h3>\n<ul>\n<li>Produced using gas welding method from steel materials.<\/li>\n<li>Electrostatic powder coating has been applied to resist rust.<\/li>\n<li>Can be anchored to the ground.<\/li>\n<li>Modular design allows for part replacement.<\/li>\n<\/ul>\n<div class=\"is-divider divider clearfix\" style=\"margin-top:30px;margin-bottom:30px;max-width:100%;height:1px;\"><\/div>\n<h3>Trash Cans<\/h3>\n\t<div id=\"gap-263027250\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-263027250 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p>Your gardens, parks, and sidewalks are the areas where you spend the most time and find peace. Therefore, a clean and organized environment is crucial both aesthetically and for health reasons. Outdoor trash bins are practical and effective solutions that help keep our surroundings clean and organized at all times.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t<div id=\"gap-589402601\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-589402601 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 41px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(52, 53, 55);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewBox=\"0 0 28.3 28.3\">\n  <defs>\n    <style>\n      .cls-1 {\n        fill: #26333c;\n      }\n    <\/style>\n  <\/defs>\n  <!-- Generator: Adobe Illustrator 28.7.1, SVG Export Plug-In . SVG Version: 1.2.0 Build 142)  -->\n  <g>\n    <g id=\"Layer_1\">\n      <g>\n        <path class=\"cls-1\" d=\"M12.6,11c.2,0,.5-.2.5-.4,0-.3-.1-.5-.4-.6l-5.9-1.1c-.3,0-.5.1-.6.4,0,.3.1.5.4.6l5.9,1.1s0,0,0,0Z\"\/>\n        <path class=\"cls-1\" d=\"M13.7,8.3c0-.3-.1-.5-.4-.6l-5-.9c-.3,0-.5.1-.6.4s.1.5.4.6l5,.9s0,0,0,0c.2,0,.4-.2.5-.4Z\"\/>\n        <path class=\"cls-1\" d=\"M5.5,4.9l8.1,1.5s0,0,0,0c.2,0,.5-.2.5-.4,0-.3-.1-.5-.4-.6l-8.1-1.5c-.3,0-.5.1-.6.4s.1.5.4.6Z\"\/>\n        <path class=\"cls-1\" d=\"M6.5,16.9c-.2.2-.2.5,0,.7l.8.8c0,.1.2.2.4.2s.3,0,.3-.1c.2-.2.2-.5,0-.7l-.8-.8c-.2-.2-.5-.2-.7,0Z\"\/>\n        <path class=\"cls-1\" d=\"M8,14.7c-.2-.2-.5-.2-.7,0l-.9.9c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1l.9-.9c.2-.2.2-.5,0-.7Z\"\/>\n        <path class=\"cls-1\" d=\"M5.2,16.2c0,.1.2.2.4.2s.2,0,.3-.1c.2-.2.2-.5,0-.7l-.8-.8c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7l.8.8Z\"\/>\n        <path class=\"cls-1\" d=\"M4.3,18.4c0,0,.2.1.3.1s.3,0,.4-.2l.8-.9c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.9c-.2.2-.2.5,0,.7Z\"\/>\n        <path class=\"cls-1\" d=\"M3.4,11.8c-.3,0-.5.2-.5.5v.9c0,.3.2.5.5.5s.5-.2.5-.5v-.9c0-.3-.2-.5-.5-.5Z\"\/>\n        <path class=\"cls-1\" d=\"M4.3,11.8h1c.3,0,.5-.2.5-.5s-.2-.5-.5-.5h-1c-.3,0-.5.2-.5.5s.2.5.5.5Z\"\/>\n        <path class=\"cls-1\" d=\"M3.4,10.9c.3,0,.5-.2.5-.5v-.9c0-.3-.2-.5-.5-.5s-.5.2-.5.5v.9c0,.3.2.5.5.5Z\"\/>\n        <path class=\"cls-1\" d=\"M1.5,11.9h1.1c.3,0,.5-.2.5-.5s-.2-.5-.5-.5h-1.1c-.3,0-.5.2-.5.5s.2.5.5.5Z\"\/>\n        <path class=\"cls-1\" d=\"M23.2,14.7c.8,0,1.5-.7,1.5-1.5s-.7-1.5-1.5-1.5-1.5.7-1.5,1.5.7,1.5,1.5,1.5ZM23.2,12.7c.3,0,.5.2.5.5s-.2.5-.5.5-.5-.2-.5-.5.2-.5.5-.5Z\"\/>\n        <path class=\"cls-1\" d=\"M26.3,17.9c.9,0,1.7-.8,1.7-1.7s-.8-1.7-1.7-1.7-1.7.8-1.7,1.7.8,1.7,1.7,1.7ZM26.3,15.6c.4,0,.7.3.7.7s-.3.7-.7.7-.7-.3-.7-.7.3-.7.7-.7Z\"\/>\n        <path class=\"cls-1\" d=\"M26,21.4c-.3-1.3-1.6-2.6-3.4-2.6s-2.1.6-2.5,1c-.6-.5-1.5-.4-1.5-.4,0,0,0,0,0,0,0,0,0,0-.1,0,0-.8,0-1.5-.2-2.1,0,0,0,0,0-.1-.3-.9-.7-1.6-1.4-2.1l2.7-13.3s0,0,0-.1c0-.4-.3-1.3-1.3-1.6-1-.3-1.7.4-1.9.8,0,0,0,.1,0,.2l-2.8,13.3c-.9.4-1.4,1.2-1.7,1.8-1.9,4.8-11.2,6.1-11.3,6.1-.2,0-.3.1-.4.3s0,.3,0,.5c0,0,1.2,2.2,3.7,3.7,1.2.8,3,1.4,5.2,1.5,0,0,0,0,.1,0s0,0,0,0c0,0,.2,0,.2,0,1.8,0,3.9-.4,6.2-1.4.5.3,1,.4,1.3.4s.9-.1,1.2-.3c.4.5,1.3,1.4,3,1.4s2.5-.7,2.9-1.1c.3.1.8.2,1.2.2,1.9,0,3-1.1,3-3s-1.4-2.8-2.3-3.1ZM17.1,1.3c.1-.1.4-.4.8-.3.4.1.5.5.5.6l-2.6,12.9c-.2,0-.4-.2-.6-.2-.3,0-.5-.1-.7-.1l2.7-12.8ZM14.9,15.2c1,.3,1.8.8,2.2,1.9-.4.2-1.2.5-2.2.5s-1.9-.7-2.3-1.1c0-.2.8-1.7,2.2-1.2ZM3.1,24.9c2.1-.3,4.7-1.5,4.9-1.5.3-.1.4-.4.2-.7-.1-.2-.4-.4-.7-.2-1,.5-3.9,1.6-5.4,1.5-.3-.3-.5-.6-.7-.9,2.2-.4,8.5-1.9,10.9-5.7.6.5,1.6,1.2,2.7,1.2s1.9-.3,2.4-.5c0,.5,0,1,0,1.7-.9.5-1.3,1.4-1.4,2-.8.4-1.8,1.4-1.8,2.8s.2,1.1.5,1.5c-1.2.5-2.3.8-3.4,1,1-.7,1.7-1.5,1.7-1.6.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0,0,0-1.7,1.9-3.4,2.4-1,0-1.9-.2-2.7-.5,4-1.1,6.8-4.7,6.9-4.9.2-.2.1-.5-.1-.7-.2-.2-.5-.1-.7,0,0,0-3.4,4.4-7.7,4.7,0,0-.2,0-.3-.1-.5-.3-.9-.6-1.3-.9ZM25.3,26.4c-.4,0-1-.2-1.2-.3-.2-.1-.5,0-.7.2,0,0-.6,1-2.3,1s-2.3-1.2-2.3-1.2c0-.1-.2-.2-.3-.3,0,0-.1,0-.2,0,0,0-.2,0-.2,0-.2,0-.7.4-1.1.4s-1.6-.5-1.6-1.6,1-1.9,1.2-2c.1,0,.3,0,.4-.2,0,0,.1-.2.1-.4,0-.2,0-1.5,1.6-1.8.2,0,.8,0,1,.4,0,.2.2.3.4.3.2,0,.3,0,.4-.2,0,0,.8-1,2.1-1s2.4,1.2,2.4,2c0,.2.2.4.4.5.2,0,1.8.3,1.8,2.2s-.6,2-2,2Z\"\/>\n        <path class=\"cls-1\" d=\"M22.6,20.7c-.7,0-1.3.6-1.4.7-.2.2-.2.5,0,.7.2.2.5.2.7,0,.1-.1.4-.4.7-.4s.7.3.7.7.2.5.5.5.5-.2.5-.5c0-1-.9-1.7-1.7-1.7Z\"\/>\n      <\/g>\n    <\/g>\n  <\/g>\n<\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p>Outdoor trash bins provide a way to collect daily waste, food scraps, and other litter that accumulates in areas such as parks and gardens in an organized manner.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t<div id=\"gap-618905206\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-618905206 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 41px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(52, 53, 55);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewBox=\"0 0 28.3 28.3\">\n  <defs>\n    <style>\n      .cls-1 {\n        fill: #26333c;\n      }\n    <\/style>\n  <\/defs>\n  <!-- Generator: Adobe Illustrator 28.7.1, SVG Export Plug-In . SVG Version: 1.2.0 Build 142)  -->\n  <g>\n    <g id=\"Layer_1\">\n      <g>\n        <path class=\"cls-1\" d=\"M25.4,17.1c.1-.3.2-.7-.1-1.2-.6-1.1-1.6-1.1-2.1-1l-1.6.5c0,0-.2,0-.3-.1,0-.7,0-1.7,0-2.2l.3-.2c.7.2,1.8.5,2.2.5.7,0,1.4-.5,1.4-1.5s-.1-.8-.3-1.1c.3-.3.5-.7.5-1.2,0-1.1-1-1.6-1.5-1.6s-.3,0-.4.1c-.3-.7-.9-1-1.5-1-.8,0-1.4.9-1.4,1,0,0,0,0,0,.1l-.5,1.8-.3.2c-.6-.6-1.5-1-2-1.2h0c0,0,1.6-1.8,1.6-1.8,0,0,0-.1.1-.2,0,0,.2-.8-.2-1.6-.3-.6-.9-.6-1.4-.6,0-.3-.2-.6-.3-.7-.3-.4-.7-.6-1.3-.6s-.5,0-.7.2v-1.7h0V.5c0-.3-.2-.5-.5-.5s-.5.2-.5.5v1.2l-1.9,2c-.2.2-.2.5,0,.7,0,0,.2.1.3.1s.2,0,.3-.1l1.3-1.3v3.7c-3.8.1-6.8,3.4-6.8,7.3s3,7.2,6.8,7.3v3.7l-1.3-1.3c-.2-.2-.5-.2-.7,0s-.2.5,0,.7l1.9,2v1.3c0,.3.2.5.5.5s.5-.2.5-.5v-1.5h0v-1.6c.2,0,.5.1.8.1s.7-.1,1-.4c.2-.2.3-.5.4-.8h.2c0,0,0,0,0,0,.3,0,1,0,1.3-.8.3-.7.2-1.3,0-1.7,0,0,0,0,0-.1l-1.4-1.5v-.2c.8-.3,1.5-.9,1.9-1.2h.2c0,.1.5,2,.5,2,0,0,0,0,0,.1.2.3.7.9,1.5.9s1-.5,1.2-1c.1,0,.2,0,.3,0,.9,0,1.8-.7,1.8-1.5s-.2-.7-.4-1c.2-.1.3-.3.4-.6ZM8.8,14.1c0-3.4,2.6-6.2,5.8-6.3v12.6c-3.2-.1-5.8-2.9-5.8-6.3ZM24.5,16.7c0,.2-.3.3-.5.4-.2,0-.3.2-.3.4,0,.2,0,.4.2.5.3.2.6.6.6.8,0,.2-.3.5-.8.5s-.2,0-.2,0c0-.1-.2-.2-.3-.2-.2,0-.5.1-.5.4,0,0,0,0,0,0,0,0-.1.8-.4.8s-.6-.2-.7-.3l-.6-2.1c0-.1-.1-.3-.3-.3l-.7-.4c-.2,0-.4,0-.6.1,0,0-.9,1.1-2,1.3-.2,0-.4.2-.4.5v.8c0,.1,0,.3.1.4l1.5,1.6c0,.1.1.4,0,.7-.1.2-.3.3-.4.3l-.7-.2c-.1,0-.3,0-.4,0-.1.1-.2.3-.2.4,0,.2,0,.6-.2.7,0,0-.1.1-.3.1-.6,0-.7-.3-.7-.3h0s0-18.2,0-18.2c0,0,0,0,0-.1.2-.4.4-.7.6-.7.2,0,.4,0,.5.2,0,.1.1.3,0,.6,0,.2,0,.3.1.5.1.1.3.2.5.1.4-.1.9-.1,1,0,.2.3.2.6.1.7l-1.6,1.8c0,0-.1.2-.1.3v.6c0,.2.1.4.3.5.6.2,1.8.7,2.1,1.3,0,.1.2.2.3.3.1,0,.3,0,.4,0l.8-.6c0,0,.2-.2.2-.3l.5-1.9c.1-.2.4-.4.6-.4s.6,0,.6.8,0,.4.3.4c.2,0,.3,0,.5,0,.2-.1.5-.3.5-.3,0,0,.5,0,.5.6s-.4.6-.4.7c-.2,0-.3.2-.3.4,0,.2,0,.4.2.5,0,0,.3.2.3.7s0,.5-.5.5c-.2,0-1.3-.3-2.1-.6-.1,0-.3,0-.4,0l-.8.5c-.2.1-.3.3-.2.5.1,1,.2,2.2,0,2.6,0,.2,0,.3,0,.5,0,.1.2.2.4.3.2,0,.4,0,.4,0,.1.2.3.2.5.2l1.9-.6c0,0,.6-.1.9.5,0,.1,0,.3,0,.3Z\"\/>\n        <path class=\"cls-1\" d=\"M9.9,22.4h-2.5v-2.6c0-.3-.2-.5-.5-.5s-.5.2-.5.5v3.1c0,.3.2.5.5.5h3c.3,0,.5-.2.5-.5s-.2-.5-.5-.5Z\"\/>\n        <path class=\"cls-1\" d=\"M5.8,11.6c-.2-.2-.5-.2-.7,0l-2.1,2.2c-.2.2-.2.5,0,.7l2.1,2.2c0,0,.2.1.3.1s.2,0,.3-.1c.2-.2.2-.5,0-.7l-1.8-1.8,1.8-1.8c.2-.2.2-.5,0-.7Z\"\/>\n        <path class=\"cls-1\" d=\"M6.9,9c.3,0,.5-.2.5-.5v-2.6h2.5c.3,0,.5-.2.5-.5s-.2-.5-.5-.5h-3c-.3,0-.5.2-.5.5v3.1c0,.3.2.5.5.5Z\"\/>\n      <\/g>\n    <\/g>\n  <\/g>\n<\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p>It is resistant to various weather conditions such as rain, snow, and sun; it has rust-resistant and waterproof features.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t<div id=\"gap-1143640041\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1143640041 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 41px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(52, 53, 55);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewBox=\"0 0 28.3 28.3\">\n  <defs>\n    <style>\n      .cls-1 {\n        fill: #26333c;\n      }\n    <\/style>\n  <\/defs>\n  <!-- Generator: Adobe Illustrator 28.7.1, SVG Export Plug-In . SVG Version: 1.2.0 Build 142)  -->\n  <g>\n    <g id=\"Layer_1\">\n      <g>\n        <path class=\"cls-1\" d=\"M27.8,0H10.4c-.3,0-.5.2-.5.5v4.4h-4.6c-.3,0-.5.2-.5.5v4.4H.5C.2,9.8,0,10,0,10.3v17.6C0,28.1.2,28.3.5,28.3h17.4c.3,0,.5-.2.5-.5v-3.4h0v-.9h4.4c.3,0,.5-.2.5-.5v-4.4h4.6c.3,0,.5-.2.5-.5V.5c0-.3-.2-.5-.5-.5ZM6.9,10.8l.8.8c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7h-.1c0-.1,1.7-.1,1.7-.1l.8.8c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7h-.1c0-.1,1.9-.1,1.9-.1l.8.8c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7h-.1c0-.1,2.7-.1,2.7-.1v2.7h0c-.2-.3-.5-.3-.7,0-.2.2-.2.5,0,.7l.8.8v1.9l-.3-.3c-.2-.2-.5-.2-.7,0s-.2.5,0,.7l.9.9s0,0,0,0v1.7h-.1c-.2-.3-.5-.3-.7-.1-.2.2-.2.5,0,.7l.8.9v1.9h0c-.2-.3-.5-.3-.7,0s-.2.5,0,.7l.8.8v1.9h0c-.2-.3-.5-.3-.7,0s-.2.5,0,.7h.1c0,.1-1.9.1-1.9.1l-.8-.9c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7h.1c0,.1-1.9.1-1.9.1,0,0,0,0,0,0l-.9-.9c-.2-.2-.5-.2-.7,0s-.2.5,0,.7l.2.2h-1.9s0,0,0,0l-.9-.9c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7l.2.2h-1.9l-.8-.8c-.2-.2-.5-.2-.7,0s-.2.5,0,.7h0c0,0-1.9,0-1.9,0l-.7-.7v-1.9h0c0,.2.2.2.4.2s.3,0,.4-.1c.2-.2.2-.5,0-.7l-.8-.8v-1.9h0c0,.2.2.2.4.2s.3,0,.4-.1c.2-.2.2-.5,0-.7l-.8-.8v-1.9l.2.2c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7l-.9-.9v-1.9l.2.2c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7l-.9-.9v-1.9h0c0,.2.2.2.4.2s.3,0,.4-.1c.2-.2.2-.5,0-.7h0c0,0,1.9,0,1.9,0l.8.8c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7h-.1c0-.1,1.9-.1,1.9-.1ZM22.3,22.5h-3.9v-12.2c0-.3-.2-.5-.5-.5H5.9v-3.8h16.4v16.5ZM27.3,17.6h-4.1V5.4c0-.3-.2-.5-.5-.5h-11.9V1h16.4v16.5Z\"\/>\n        <path class=\"cls-1\" d=\"M2.7,13.3l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1Z\"\/>\n        <path class=\"cls-1\" d=\"M3.6,14.1l.9.9c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7l-.9-.9c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7Z\"\/>\n        <path class=\"cls-1\" d=\"M8.9,20.1c.1,0,.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1Z\"\/>\n        <path class=\"cls-1\" d=\"M11.1,21.6c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7l-.9-.9c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7l.9.9Z\"\/>\n        <path class=\"cls-1\" d=\"M6,15l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0Z\"\/>\n        <path class=\"cls-1\" d=\"M7.5,16.5c-.2-.2-.5-.2-.7,0s-.2.5,0,.7l.9.9c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7l-.9-.9Z\"\/>\n        <path class=\"cls-1\" d=\"M15.9,25l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0Z\"\/>\n        <path class=\"cls-1\" d=\"M12.1,23.2c.1,0,.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1Z\"\/>\n        <path class=\"cls-1\" d=\"M14.9,24l-.9-.9c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7l.9.9c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7Z\"\/>\n        <path class=\"cls-1\" d=\"M5.6,20.1c.1,0,.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1Z\"\/>\n        <path class=\"cls-1\" d=\"M8.1,21.7c.1,0,.3,0,.4-.1.2-.2.2-.5,0-.7l-.9-.9c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7l.9.9c0,0,.2.1.4.1Z\"\/>\n        <path class=\"cls-1\" d=\"M2.6,16.5l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1Z\"\/>\n        <path class=\"cls-1\" d=\"M4.1,16.5c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7l.9.9c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7l-.9-.9Z\"\/>\n        <path class=\"cls-1\" d=\"M12.6,25l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0Z\"\/>\n        <path class=\"cls-1\" d=\"M8.8,23.2c.1,0,.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1Z\"\/>\n        <path class=\"cls-1\" d=\"M11.6,24l-.9-.9c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7l.9.9c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7Z\"\/>\n        <path class=\"cls-1\" d=\"M5.7,23.4c.1,0,.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1Z\"\/>\n        <path class=\"cls-1\" d=\"M8.5,24.2l-.9-.9c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7l.9.9c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7Z\"\/>\n        <path class=\"cls-1\" d=\"M2.6,19.9l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1Z\"\/>\n        <path class=\"cls-1\" d=\"M3.5,20.6l.9.9c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7l-.9-.9c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7Z\"\/>\n        <path class=\"cls-1\" d=\"M9.2,24.9l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0Z\"\/>\n        <path class=\"cls-1\" d=\"M2.3,23.4c.1,0,.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1Z\"\/>\n        <path class=\"cls-1\" d=\"M5.2,24.2l-.9-.9c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7l.9.9c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7Z\"\/>\n        <path class=\"cls-1\" d=\"M5.9,24.9l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0Z\"\/>\n        <path class=\"cls-1\" d=\"M2.8,25.1l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0Z\"\/>\n        <path class=\"cls-1\" d=\"M12.7,15.1l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0Z\"\/>\n        <path class=\"cls-1\" d=\"M15.1,17.5l-.9-.9c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7l.9.9c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7Z\"\/>\n        <path class=\"cls-1\" d=\"M8.9,13.4c.1,0,.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1Z\"\/>\n        <path class=\"cls-1\" d=\"M10.1,13.9l.9.9c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7l-.9-.9c-.2-.2-.5-.2-.7,0s-.2.5,0,.7Z\"\/>\n        <path class=\"cls-1\" d=\"M15.8,18.2l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0Z\"\/>\n        <path class=\"cls-1\" d=\"M9.4,15.1l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0Z\"\/>\n        <path class=\"cls-1\" d=\"M10.1,16.6c-.2.2-.2.5,0,.7l.9.9c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7l-.9-.9c-.2-.2-.5-.2-.7,0Z\"\/>\n        <path class=\"cls-1\" d=\"M5.2,13.2c0,0,.2.1.4.1s.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7Z\"\/>\n        <path class=\"cls-1\" d=\"M6.8,13.9l.9.9c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7l-.9-.9c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7Z\"\/>\n        <path class=\"cls-1\" d=\"M15.9,21.6l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0Z\"\/>\n        <path class=\"cls-1\" d=\"M12.4,19.7l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1Z\"\/>\n        <path class=\"cls-1\" d=\"M14.5,21.5c.1,0,.3,0,.4-.1.2-.2.2-.5,0-.7l-.9-.9c-.2-.2-.5-.2-.7,0s-.2.5,0,.7l.9.9c0,0,.2.1.4.1Z\"\/>\n        <path class=\"cls-1\" d=\"M15.5,13.6c.1,0,.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1Z\"\/>\n        <path class=\"cls-1\" d=\"M12.1,13.5c.1,0,.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1Z\"\/>\n        <path class=\"cls-1\" d=\"M13.3,14.1l.9.9c0,0,.2.1.4.1s.3,0,.4-.1c.2-.2.2-.5,0-.7l-.9-.9c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7Z\"\/>\n        <path class=\"cls-1\" d=\"M15.7,15l-.8.8c-.2.2-.2.5,0,.7,0,0,.2.1.4.1s.3,0,.4-.1l.8-.8c.2-.2.2-.5,0-.7-.2-.2-.5-.2-.7,0Z\"\/>\n      <\/g>\n    <\/g>\n  <\/g>\n<\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p>Buckets made from materials such as steel, durable plastic, or composite offer long-lasting use.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t<div id=\"gap-1385566221\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1385566221 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 41px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(52, 53, 55);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewBox=\"0 0 28.3 28.3\">\n  <defs>\n    <style>\n      .cls-1 {\n        fill: #26333c;\n      }\n    <\/style>\n  <\/defs>\n  <!-- Generator: Adobe Illustrator 28.7.1, SVG Export Plug-In . SVG Version: 1.2.0 Build 142)  -->\n  <g>\n    <g id=\"Layer_1\">\n      <g>\n        <path class=\"cls-1\" d=\"M11.2,21.3c0-2.5-1.4-4.4-2.8-6.3-1.3-1.8-4.1-2.4-5-2.5.2-1.2.5-2.1.5-2.1,0-.3,0-.6-.3-.6-.3,0-.5,0-.6.3,0,0-.4,1.2-.7,2.8C.9,14.1-.3,16.4,0,19.6c1,8.2,8,8.4,8.6,8.4s0,0,0,0h2c.2,0,.4-.1.4-.3,0-.2,0-.4,0-.5-.5-.7-.3-2-.1-3.4.1-.8.2-1.6.2-2.4ZM10,23.6c-.2,1.2-.3,2.4,0,3.4h-1.2c-.3,0-6.8.1-7.7-7.5-.3-2.4.4-3.9,1.1-4.9,0,.3,0,.5,0,.8,0,1.6.6,3.7,1.5,5.5l-.5,1.8c0,.3,0,.5.3.6,0,0,0,0,.1,0,.2,0,.4-.1.5-.4l.2-.8c.5.8,1.1,1.6,1.7,2.2,0,0,.2.1.3.1s.3,0,.4-.2c.2-.2.2-.5,0-.7-.8-.7-1.5-1.7-2.1-2.9,0,0,0,0,0-.1-.5-.9-.8-1.8-1.1-2.7l1.8.9c0,0,.1,0,.2,0,.2,0,.4-.1.4-.3.1-.3,0-.6-.2-.7l-2.5-1.2c0-.4,0-.8,0-1.1,0-.7,0-1.3.1-1.9.8.1,3.3.6,4.4,2.1,1.4,1.8,2.6,3.6,2.6,5.7s-.1,1.5-.2,2.3Z\"\/>\n        <path class=\"cls-1\" d=\"M27.2,14.2l-1-1.8c0-.2-.3-.3-.4-.3-.2,0-.3.1-.4.3-.4.8-1.5,1.3-2.8,1.8-.7.3-1.5.6-2.1,1-2.1,1.2-3,3.5-3.9,5.7-.9,2.1,0,4.9.4,5.8-1.1.4-2,.6-2,.6-.3,0-.4.3-.4.6,0,.2.2.4.5.4s0,0,0,0c0,0,1.2-.2,2.7-.8.6.2,1.3.4,2.1.4,1.4,0,3-.5,4.6-1.7,6.6-5.2,2.7-11.9,2.7-11.9ZM23.9,25.4c-1.8,1.4-3.5,1.6-4.7,1.5.2-.1.5-.2.7-.4,1.4-.8,2.8-2.4,3.8-4.1l1.7-.4c.3,0,.4-.3.4-.6,0-.3-.3-.4-.6-.4l-.8.2c.4-.9.8-1.8.9-2.6,0-.3-.1-.5-.4-.6-.3,0-.5.1-.6.4-.2,1-.7,2.2-1.4,3.3,0,0,0,0,0,.1-.5.8-1.1,1.7-1.8,2.3l-.2-2c0-.3-.3-.5-.5-.5-.3,0-.5.3-.5.5l.2,2.8c-.3.2-.6.5-.9.6-.5.3-1.1.6-1.6.8-.3-.7-1.1-3.2-.4-5,.9-2.1,1.7-4.1,3.5-5.2.6-.4,1.3-.7,2-.9,1.1-.5,2.2-.9,2.9-1.6l.6,1.1c.1.2,3.5,6-2.4,10.6Z\"\/>\n        <path class=\"cls-1\" d=\"M22.2,7.3c.9.8,1.5,1.5,1.5,1.5,0,.1.2.2.4.2s.2,0,.3-.1c.2-.2.2-.5,0-.7,0,0-.8-1-2.1-2-.4-1.9-1.7-4.1-4.6-5.3-7.7-3.2-11.2,3.8-11.3,3.8l-1,1.8c0,.2,0,.4,0,.5.1.2.3.2.5.2.9-.1,1.9.7,3,1.5.6.5,1.3,1,1.9,1.4,1.1.6,2.2.8,3.4.8s2.2-.2,3.3-.3c2.2-.3,4-2.6,4.6-3.3ZM11.4,9.2c-.6-.4-1.2-.8-1.8-1.3-1-.7-1.9-1.5-2.8-1.7l.6-1.1s.8-1.6,2.4-2.8c2.2-1.6,4.7-1.8,7.6-.6,2.1.9,3.1,2.3,3.6,3.4-.2-.1-.4-.3-.7-.4-1.4-.8-3.4-1.2-5.3-1.3l-1.3-1.3c-.2-.2-.5-.2-.7,0-.2.2-.2.5,0,.7l.6.6c-1,0-1.9.2-2.7.5-.3,0-.4.4-.3.6,0,.3.4.4.6.3,1-.4,2.2-.5,3.5-.5,0,0,0,0,0,0s0,0,0,0c1,0,2,.1,2.9.3l-1.6,1.2c-.2.2-.3.5-.1.7,0,.1.2.2.4.2s.2,0,.3,0l2.2-1.7c.4.1.7.3,1,.4.6.3,1.1.7,1.5,1-.5.6-2.1,2.7-3.9,2.9-2.2.3-4.3.7-6.1-.4Z\"\/>\n      <\/g>\n    <\/g>\n  <\/g>\n<\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p>With their natural colors and modern designs, they provide an aesthetically pleasing and environmentally friendly look for parks.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t<div id=\"gap-1492124690\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1492124690 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 41px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(52, 53, 55);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewBox=\"0 0 28.3 28.3\">\n  <defs>\n    <style>\n      .cls-1 {\n        fill: #26333c;\n      }\n    <\/style>\n  <\/defs>\n  <!-- Generator: Adobe Illustrator 28.7.1, SVG Export Plug-In . SVG Version: 1.2.0 Build 142)  -->\n  <g>\n    <g id=\"Layer_1\">\n      <path class=\"cls-1\" d=\"M28.2,27.4c0,0-5.9-4.6-6.7-5.4-.7-.6-.6-1.4-.6-1.4,0,0,0,0,0,0v-2c0-1.8-1.2-2.9-1.4-3.1l-1.2-1.2,1.9-2,.4.3c.2.2.5.2.7,0,0,0,.7-.5,1.5-.5s1.1.8,1.1.9l1.2,2.7c0,.2.3.3.5.3,0,0,0,0,0,0,.2,0,.4-.1.5-.3,2-3.5.7-6.4.6-6.6,0,0,0,0,0-.1l-5.5-5.7c0-.1-.2-.2-.4-.2-.1,0-.3,0-.4.1-.3.3-.9.7-1.1.5-.2-.2,0-1.1.3-1.6.1-.2,0-.4-.1-.6l-1.8-1.7c-.2-.2-.6-.2-.8,0l-4.2,4c-.2.2-.2.5,0,.7l1.7,1.8c.2.2.5.2.7,0,0,0,1.2-.8,1.6-.3.1.1.1.2.1.3,0,.3-.5.6-.7.7-.1,0-.2.2-.3.4,0,.2,0,.3.1.4l.3.3-4,3.7-1-.9c-.4-.3-.9-.5-1.4-.5-.5,0-1,.2-1.3.6-.3.3-.5.7-.5,1-.1,0-.3,0-.4,0-.5,0-1,.2-1.3.6-.4.4-.5.8-.5,1.3,0,.2,0,.4.1.6-.5,0-.9.2-1.2.6-.4.4-.5.8-.5,1.3,0,.4.1.7.3,1-.3,0-.6.3-.8.5-.4.4-.6.8-.5,1.4,0,.4.1.7.4,1-.7.7-2.4,2.2-3.1,2.8-.9.9-.5,1.9-.2,2.4,0,0,0,0,0,0l1.5,1.4s0,0,.1,0c0,0,.6.2,1.1.2s1.3-.5,1.4-.7l2.9-2.7c2.9,2.7,4.5,2.8,5.7,2.9,0,0,.2,0,.2,0,.9,0,1.5,1,1.5,1,.1.2.3.3.5.3s.2,0,.3,0c.3-.1.3-.5.2-.7,0,0-.9-1.4-2.3-1.5,0,0-.2,0-.3,0-1,0-2.5-.2-5.1-2.6l6-5.8c0,.1,0,.3,0,.4,0,1.5,1,2.2,1,2.2.2.2.6.1.8-.1.2-.2.1-.5-.1-.7,0,0-.6-.4-.6-1.4s.7-1.9.7-1.9c.2-.2.1-.5,0-.7l-.3-.3c-.1-.1-.3-.2-.4-.1-.2,0-.3,0-.4.2s-.8,1-2.1,1-.8,0-1.1-.2c0,0,0,0,0-.2,0-.2,0-.3,0-.5l.7-.7,1.4-1.3c0,0,.5-.3,1-.3s.8.1.8.2l3.1,2.9s0,0,0,0c0,0,1,.9,1,2.3v2c0,.2,0,1.4.9,2.3s6.5,5.3,6.8,5.5c.1,0,.2.1.3.1s.3,0,.4-.2c.2-.2.2-.5,0-.7ZM14.9,5.6l-1-1.1,3.5-3.3,1.1,1.1c-.3.6-.6,1.7.1,2.4.6.6,1.5.3,2.2-.2l5,5.2c.2.4.8,2.2-.1,4.6l-.8-1.7s0,0,0,0c0,0-.8-1.5-2.1-1.5s-1.4.2-1.8.4l-3.8-3.7c.3-.2.6-.6.7-1,0-.4,0-.8-.3-1.1-.7-.9-1.9-.6-2.7-.2ZM9.5,12.1c.2-.2.4-.2.6-.3,0,0,0,0,0,0,.2,0,.4,0,.6.2l1.5,1.3-.6.6-.6.6-.9-.8-.6-.5c-.3-.3-.4-.8,0-1.1ZM7.2,13.7c.2-.2.4-.2.6-.3,0,0,0,0,0,0,.2,0,.4,0,.6.2l.4.3s0,0,0,0l1.4,1.3-.2.2c-.2.2-.2.5,0,.7,0,0,.2.2.4.4l-.6.6-2.6-2.3c-.2-.1-.3-.3-.3-.6s0-.4.2-.6ZM5.6,16.1c.2-.2.4-.2.6-.3,0,0,0,0,0,0,.2,0,.4,0,.6.2l1.7,1.5c.2.1.3.3.3.6s0,.4-.2.6c-.2.2-.4.2-.6.3-.2,0-.4,0-.6-.2l-.7-.6s0,0,0,0l-1-.9c-.2-.1-.3-.3-.3-.6s0-.4.2-.6ZM4.6,18.9c.2-.2.4-.3.6-.3,0,0,0,0,0,0,.2,0,.5,0,.6.2l.4.3.3.3s0,0,0,0h.1c.4.4.4,1,0,1.3-.3.3-.9.4-1.3,0l-.8-.7c-.2-.2-.3-.4-.3-.6s0-.5.2-.6ZM12.8,17.3c.2,0,.3,0,.4,0L3.9,26.2c-.2.2-.5.4-.7.4-.2,0-.5,0-.6-.1l-1.4-1.3c0-.2-.3-.7,0-1.1.6-.6,2.3-2.1,3-2.8l.4.3c.4.3.9.5,1.4.5s1.1-.2,1.5-.6c.4-.4.6-1,.5-1.5.5,0,.9-.2,1.2-.6h0c.3-.3.5-.7.5-1.1,0,0,0,0,0,0,.1,0,.3,0,.4-.2l.9-1h0c0,0,.1-.1.2-.2.4.1.9.2,1.4.2ZM16.4,12.4c0,0-.6-.4-1.5-.4s-.5,0-.8.1l3.1-2.9,2.3,2.3-2,2-1.1-1.1s0,0,0,0Z\"\/>\n    <\/g>\n  <\/g>\n<\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p>Thanks to their optionally fixed structures, they do not topple due to natural conditions or human intervention, ensuring safe usage.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:30px;margin-bottom:30px;max-width:100%;height:1px;background-color:rgba(0, 0, 0, 0);\"><\/div>\n\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n wdtVerticalScroll\"\n    >\n        <table id=\"wpdtSimpleTable-15\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"11\"\n           data-rows=\"3\"\n           data-wpID=\"15\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell wpdt-fs-000016 wpdt-bold wpdt-bc-CDCDCD wpdt-merged-cell \"\n                     colspan=\"11\"  rowspan=\"1\"                     data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:101.85185185185%;                    padding:7px;\n                    \"\n                    >\n                                        STANDARD RAL CODES                    <\/td>\n                                                                                                                                                                <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell wpdt-bc-F2F2F2 wpdt-empty-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                                            <\/td>\n                                                <td class=\"wpdt-cell wpdt-sc-FFD700 wpdt-bc-4F5250 wpdt-empty-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                                            <\/td>\n                                                <td class=\"wpdt-cell wpdt-bc-383E42 wpdt-empty-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                                            <\/td>\n                                                <td class=\"wpdt-cell wpdt-bc-EEB700 wpdt-empty-cell \"\n                                            data-cell-id=\"D2\"\n                    data-col-index=\"3\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                                            <\/td>\n                                                <td class=\"wpdt-cell wpdt-bc-0B7BB0 wpdt-empty-cell \"\n                                            data-cell-id=\"E2\"\n                    data-col-index=\"4\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                                            <\/td>\n                                                <td class=\"wpdt-cell wpdt-bc-FF9C00 wpdt-empty-cell \"\n                                            data-cell-id=\"F2\"\n                    data-col-index=\"5\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                                            <\/td>\n                                                <td class=\"wpdt-cell wpdt-bc-FF703C wpdt-empty-cell \"\n                                            data-cell-id=\"G2\"\n                    data-col-index=\"6\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                                            <\/td>\n                                                <td class=\"wpdt-cell wpdt-bc-007577 wpdt-empty-cell \"\n                                            data-cell-id=\"H2\"\n                    data-col-index=\"7\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                                            <\/td>\n                                                <td class=\"wpdt-cell wpdt-bc-0E0E10 wpdt-empty-cell \"\n                                            data-cell-id=\"I2\"\n                    data-col-index=\"8\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                                            <\/td>\n                                                <td class=\"wpdt-cell wpdt-bc-B81D13 wpdt-empty-cell \"\n                                            data-cell-id=\"J2\"\n                    data-col-index=\"9\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                                            <\/td>\n                                                <td class=\"wpdt-cell wpdt-bc-ECECE7 wpdt-empty-cell \"\n                                            data-cell-id=\"K2\"\n                    data-col-index=\"10\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                                            <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell wpdt-bc-F2F2F2\"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                        RAL                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                        7043                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                        7016                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"D3\"\n                    data-col-index=\"3\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                        1021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"E3\"\n                    data-col-index=\"4\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                        5015                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"F3\"\n                    data-col-index=\"5\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                        1028                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"G3\"\n                    data-col-index=\"6\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                        6029                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"H3\"\n                    data-col-index=\"7\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                        5021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"I3\"\n                    data-col-index=\"8\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                        9005                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"J3\"\n                    data-col-index=\"9\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                        3020                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"K3\"\n                    data-col-index=\"10\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:7px;\n                    \"\n                    >\n                                        9003                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-15'>\n.wpDataTables.wpDataTablesWrapper.wdtVerticalScroll  { overflow-y:auto; height:0px; }\n.wpDataTableContainerSimpleTable .wdt-res-wrapper.active  {overflow: initial; max-height:0px !important; }\n.wpdt-fs-000016 { font-size: 16px !important;}\n.wpdt-bc-CDCDCD { background-color: #CDCDCD !important;}\n.wpdt-bc-F2F2F2 { background-color: #F2F2F2 !important;}\n.wpdt-sc-FFD700 .rating > span.full.rated:after { color: #FFD700 !important;}\n.wpdt-sc-FFD700 .rating > .half:before { color: #FFD700 !important;}\n.wpdt-bc-4F5250 { background-color: #4F5250 !important;}\n.wpdt-bc-383E42 { background-color: #383E42 !important;}\n.wpdt-bc-EEB700 { background-color: #EEB700 !important;}\n.wpdt-bc-0B7BB0 { background-color: #0B7BB0 !important;}\n.wpdt-bc-FF9C00 { background-color: #FF9C00 !important;}\n.wpdt-bc-FF703C { background-color: #FF703C !important;}\n.wpdt-bc-007577 { background-color: #007577 !important;}\n.wpdt-bc-0E0E10 { background-color: #0E0E10 !important;}\n.wpdt-bc-B81D13 { background-color: #B81D13 !important;}\n.wpdt-bc-ECECE7 { background-color: #ECECE7 !important;}\n<\/style>\n\n","protected":false},"excerpt":{"rendered":"<p>Profiled Square Model Trash Can Rainproof, Impact Resistant and a customizable product for the customer with many add-ons<\/p>\n","protected":false},"featured_media":992,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[62,55],"product_tag":[],"class_list":["post-2707","product","type-product","status-publish","has-post-thumbnail","product_cat-garden-type-trash-cans1","product_cat-trash-cans1","first","instock","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/bdbmetal.com\/en\/wp-json\/wp\/v2\/product\/2707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bdbmetal.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bdbmetal.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bdbmetal.com\/en\/wp-json\/wp\/v2\/comments?post=2707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bdbmetal.com\/en\/wp-json\/wp\/v2\/media\/992"}],"wp:attachment":[{"href":"https:\/\/bdbmetal.com\/en\/wp-json\/wp\/v2\/media?parent=2707"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bdbmetal.com\/en\/wp-json\/wp\/v2\/product_brand?post=2707"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bdbmetal.com\/en\/wp-json\/wp\/v2\/product_cat?post=2707"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bdbmetal.com\/en\/wp-json\/wp\/v2\/product_tag?post=2707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}